{"id":806,"date":"2017-02-09T11:59:58","date_gmt":"2017-02-09T11:59:58","guid":{"rendered":"http:\/\/dummy.xtemos.com\/basel\/vers\/?page_id=806"},"modified":"2025-04-23T14:33:20","modified_gmt":"2025-04-23T06:33:20","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/new.zenigma.hk\/en\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1450202610956 vc_row-has-fill vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-6 vc_col-md-6\"><div class=\"vc_column-inner vc_custom_1745378677838\"><div class=\"wpb_wrapper\">\n        <div class=\"google-map-container\" data-map-args='{\"latitude\":\"22.3364951\",\"longitude\":\"114.196809\",\"zoom\":\"17\",\"mouse_zoom\":\"yes\",\"init_type\":\"page_load\",\"init_offset\":\"100\",\"json_style\":\"[\\n    {\\n        \\\"featureType\\\": \\\"all\\\",\\n        \\\"elementType\\\": \\\"all\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"hue\\\": \\\"#ff0000\\\"\\n            },\\n            {\\n                \\\"saturation\\\": -100\\n            },\\n            {\\n                \\\"lightness\\\": -30\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"all\\\",\\n        \\\"elementType\\\": \\\"labels.text.fill\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"color\\\": \\\"#ffffff\\\"\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"all\\\",\\n        \\\"elementType\\\": \\\"labels.text.stroke\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"color\\\": \\\"#353535\\\"\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"landscape\\\",\\n        \\\"elementType\\\": \\\"geometry\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"color\\\": \\\"#656565\\\"\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"poi\\\",\\n        \\\"elementType\\\": \\\"geometry.fill\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"color\\\": \\\"#505050\\\"\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"poi\\\",\\n        \\\"elementType\\\": \\\"geometry.stroke\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"color\\\": \\\"#808080\\\"\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"road\\\",\\n        \\\"elementType\\\": \\\"geometry\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"color\\\": \\\"#454545\\\"\\n            }\\n        ]\\n    },\\n    {\\n        \\\"featureType\\\": \\\"transit\\\",\\n        \\\"elementType\\\": \\\"labels\\\",\\n        \\\"stylers\\\": [\\n            {\\n                \\\"hue\\\": \\\"#000000\\\"\\n            },\\n            {\\n                \\\"saturation\\\": 100\\n            },\\n            {\\n                \\\"lightness\\\": -40\\n            },\\n            {\\n                \\\"invert_lightness\\\": true\\n            },\\n            {\\n                \\\"gamma\\\": 1.5\\n            }\\n        ]\\n    }\\n]\",\"marker_icon\":\"https:\\\/\\\/new.zenigma.hk\\\/wp-content\\\/themes\\\/basel\\\/inc\\\/assets\\\/images\\\/google-icon.png\",\"marker_text_needed\":\"yes\",\"marker_text\":\"<h3 style=\\\"min-width:300px; text-align:center; margin:15px;\\\">\\u85b0\\u5f04\\u88fd\\u9999\\u7814\\u7a76\\u6240<\\\/h3>\\u9999\\u6e2f\\u4e5d\\u9f8d\\u65b0\\u84b2\\u5d17\\u5927\\u6709\\u885734\\u865f&lt;br \\\/&gt;\\n\\u65b0\\u79d1\\u6280\\u5ee3\\u58342819\\u5ba4\",\"selector\":\"basel-map-id-6a98a8131baa5\"}'>\n\n\t        \n\t        \n            <div class=\"basel-google-map-wrapper\" >\n                <div id=\"basel-map-id-6a98a8131baa5\" style=\"height:750px;\" class=\"basel-google-map without-content\"><\/div>\n            <\/div>\n\n\t                <\/div>\n\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-6 vc_col-md-6 vc_col-has-fill color-scheme-light\"><div class=\"vc_column-inner vc_custom_1486641274246\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1745378859236\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"font-size: 44px; font-weight: bold; display: inline-block; border-bottom: 3px solid white;\">\u85b0\u5f04\u88fd\u9999\u7814\u7a76\u6240<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1449328078388\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"basel-info-box2 text-left icon-alignment-left box-style-base color-scheme-light  with-animation\" onclick=\"\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t<div class=\"info-box-inner\">\n\t\t\t\t\t\t<p>\u96fb\u8a71: (852)69888486<br \/>\n\u96fb\u90f5: zenigma@zenigma.hk<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"basel-info-box2 text-left icon-alignment-left box-style-base color-scheme-light  with-animation\" onclick=\"\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t<div class=\"info-box-inner\">\n\t\t\t\t\t\t<p>\u9999\u6e2f\u4e5d\u9f8d\u65b0\u84b2\u5d17\u5927\u6709\u885734\u865f<br \/>\n\u65b0\u79d1\u6280\u5ee3\u58342819\u5ba4<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f177-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"177\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/806#wpcf7-f177-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/806#wpcf7-f177-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"177\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f177-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<p style=\"margin-bottom: 27px;\"><label>\u4f60\u7684\u540d\u5b57 (\u5fc5\u9700)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t\t<p style=\"margin-bottom: 27px;\"><label>\u96fb\u90f5\u5730\u5740 (\u5fc5\u9700)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t\t<p style=\"margin-bottom: 27px;\"><label>\u4e3b\u65e8<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<p><label>\u5167\u5bb9<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-color-white btn-style-bordered\" type=\"submit\" value=\"\u767c\u9001\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1449327186422\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<ul class=\"social-icons text-left icons-design-colored icons-size-small social-share\">\n\t\t\t\t\t\t\t\t\t<li class=\"social-facebook\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/new.zenigma.hk\/en\/contact-us\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-facebook\"><\/i><span class=\"basel-social-icon-name\">Facebook<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-x\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/new.zenigma.hk\/en\/contact-us\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-x\"><\/i><span class=\"basel-social-icon-name\">X<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-linkedin\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/new.zenigma.hk\/en\/contact-us\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-linkedin\"><\/i><span class=\"basel-social-icon-name\">LinkedIn<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-whatsapp whatsapp-desktop\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fnew.zenigma.hk%2Fen%2Fcontact-us%2F\" target=\"_blank\" class=\"\"><i class=\"fa fa-whatsapp\"><\/i><span class=\"basel-social-icon-name\">WhatsApp<\/span><\/a><\/li>\n\n                    <li class=\"social-whatsapp whatsapp-mobile\"><a rel=\"noopener noreferrer nofollow\" href=\"whatsapp:\/\/send?text=https:\/\/new.zenigma.hk\/en\/contact-us\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-whatsapp\"><\/i><span class=\"basel-social-icon-name\">WhatsApp<\/span><\/a><\/li>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-tg\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/telegram.me\/share\/url?url=https:\/\/new.zenigma.hk\/en\/contact-us\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-telegram\"><\/i><span class=\"basel-social-icon-name\">Telegram<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<style>\n    .gm-style-iw-d , .gm-style-iw-d h3{\n        color: #232323;\n    }\n<\/style>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"\u85b0\u5f04\u88fd\u9999\u7814\u7a76\u6240 \u96fb\u8a71: (852)698","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-806","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/pages\/806"}],"collection":[{"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/comments?post=806"}],"version-history":[{"count":23,"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/pages\/806\/revisions"}],"predecessor-version":[{"id":34499,"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/pages\/806\/revisions\/34499"}],"wp:attachment":[{"href":"https:\/\/new.zenigma.hk\/en\/wp-json\/wp\/v2\/media?parent=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}